{"id":1317,"date":"2021-04-15T23:10:47","date_gmt":"2021-04-15T21:10:47","guid":{"rendered":"http:\/\/aafloods.eu\/?p=1317"},"modified":"2022-03-03T17:25:22","modified_gmt":"2022-03-03T16:25:22","slug":"reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire","status":"publish","type":"post","link":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/","title":{"rendered":"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire"},"content":{"rendered":"<p>En la regi\u00f3n francesa de Pays de la Loire, donde se encuentra la Universit\u00e9 de Nantes, socia de AA-Floods, las fuertes lluvias ca\u00eddas desde principios hasta mediados de febrero del presente a\u00f1o provocaron inundaciones o evacuaciones debido al <strong>riesgo de inundaci\u00f3n<\/strong> en las ciudades de Ancenis, Rochefort-sur-Loire, varias localidades del departamento de Vend\u00e9e y localidades de las zonas h\u00famedas al suroeste de Nantes, entre otras.<\/p>\n<p>Las advertencias emitidas el 4 de febrero por M\u00e9t\u00e9oFrance para el r\u00edo Loira alcanzaron su segundo nivel m\u00e1s alto, naranja, un procedimiento nacional de advertencia de inundaciones implementado para cumplir con la Directiva europea de inundaciones de 2007. Afortunadamente, a pesar de las inundaciones y los da\u00f1os, no se registraron muertes en este per\u00edodo. Como todos los eventos de inundaciones importantes, esto nos ofrece la oportunidad de ver la <strong>pol\u00edtica de inundaciones en acci\u00f3n<\/strong>.<\/p>\n<p>En Francia, las \u00e1reas conocidas como propensas a inundaciones se clasifican como Territoires \u00e0 Risques Importants d&#8217;inondation (TRI).<\/p>\n<p>Los TRI en Pays de la Loire se muestran en el siguiente mapa en color cian:<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-1316 size-large\" src=\"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/mapa-esp-1024x724.jpg\" alt=\"\" width=\"1024\" height=\"724\" srcset=\"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/mapa-esp-1024x724.jpg 1024w, https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/mapa-esp-300x212.jpg 300w, https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/mapa-esp-768x543.jpg 768w, https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/mapa-esp-1536x1086.jpg 1536w, https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/mapa-esp.jpg 1754w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>La identificaci\u00f3n del TRI se basa en criterios nacionales para evaluar qu\u00e9 constituye un alto riesgo. Los criterios consideran una combinaci\u00f3n de riesgo de inundaci\u00f3n hidr\u00e1ulica y posibles da\u00f1os humanos y econ\u00f3micos. Como tal, gran parte de las \u00e1reas de riesgo inundadas e identificadas quedaron fuera de los TRI de Pays de la Loire en este caso. Sin embargo, podemos considerar ejemplos de c\u00f3mo la identificaci\u00f3n de TRI continu\u00f3 beneficiando a la regi\u00f3n. La evaluaci\u00f3n de cada TRI incluye la identificaci\u00f3n de puntos de inter\u00e9s fuera de los TRI. Por ejemplo, Ancenis, a pesar de estar aproximadamente a 25 km fuera del TRI de Nantes, se menciona en la evaluaci\u00f3n territorial debido a que tiene dos instalaciones integradas de prevenci\u00f3n y control de la contaminaci\u00f3n (IPPC) dentro de los 30 km de la frontera del TRI. Una designaci\u00f3n de la CIPF indica una instalaci\u00f3n con una alta capacidad de contaminaci\u00f3n. En particular, en el caso del potencial de contaminaci\u00f3n de los r\u00edos, Ancenis est\u00e1 aguas arriba del TRI de Nantes y se encuentra a lo largo de la misma v\u00eda fluvial principal (r\u00edo Loira).<\/p>\n<p>Adem\u00e1s, un beneficio muy pr\u00e1ctico de la evaluaci\u00f3n del TRI es que desencadena el desarrollo de planes locales de gesti\u00f3n del riesgo de inundaciones, denominados <strong>Estrategias Locales de Gesti\u00f3n de Riesgos de Inundaci\u00f3n (SLGRI)<\/strong>. Estos SLGRI detallan las estrategias de respuesta a inundaciones para la protecci\u00f3n y el cuidado de las poblaciones locales y los intereses econ\u00f3micos. Como se se\u00f1al\u00f3 en el SLGRI para el TRI de Nantes, \u00abTenga en cuenta que algunas acciones del SLGRI tambi\u00e9n se refieren a territorios que se extienden fuera de las fronteras del TRI\u00bb. Esto es evidente ya que el riesgo de inundaciones en las \u00e1reas de humedales al sur de Nantes se debi\u00f3 a los afluentes del r\u00edo Loira, que es la principal v\u00eda fluvial de preocupaci\u00f3n en el TRI. Por lo tanto, insistimos en la idea de que las \u00e1reas cercanas a un TRI pueden beneficiarse de estrategias y orientaci\u00f3n enfocadas localmente a pesar de estar fuera de las fronteras del TRI.<\/p>\n<p>Tal evaluaci\u00f3n de los eventos actuales pone de relieve el valor de la evaluaci\u00f3n de la pol\u00edtica de inundaciones que est\u00e1 realizando AA-FLOODS. Continuamos nuestro trabajo sabiendo las implicaciones de c\u00f3mo la pol\u00edtica europea debe traducirse en una pol\u00edtica local razonable. Como lo demostr\u00f3 uno de nuestros socios, los riesgos no siempre est\u00e1n lejos de casa.<\/p>\n<p>El SLGRI para el TRI de Nantes y otra informaci\u00f3n sobre inundaciones est\u00e1 disponible en el <strong>sitio web del departamento de Loire-Atlantique<\/strong>:<\/p>\n<p><a href=\"https:\/\/www.loire-atlantique.gouv.fr\/Politiques-publiques\/Risques-naturels-et-technologiques\/Prevention-des-risques-naturels\/De-la-directive-inondation-aux-strategie-locales-de-gestion-des-risques-inondations\">https:\/\/www.loire-atlantique.gouv.fr\/Politiques-publiques\/Risques-naturels-et-technologiques\/Prevention-des-risques-naturels\/De-la-directive-inondation-aux-strategie-locales-de-gestion-des-risques-inondations<\/a><\/p>\n<p>El informe de mapeo de riesgos para el TRI de Nantes est\u00e1 disponible en la Direction r\u00e9gionale de l\u2019environnement, de l\u2019am\u00e9nagement et du logement (DREAL) Pays de la Loire:<\/p>\n<p><a href=\"http:\/\/www.donnees.centre.developpement-durable.gouv.fr\/risques\/directive_inondation\/5_Cartes_Nantes.pdf\">http:\/\/www.donnees.centre.developpement-durable.gouv.fr\/risques\/directive_inondation\/5_Cartes_Nantes.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la regi\u00f3n francesa de Pays de la Loire, donde se encuentra la Universit\u00e9 de Nantes, socia de AA-Floods, las fuertes lluvias ca\u00eddas desde principios hasta mediados de febrero del presente a\u00f1o provocaron inundaciones o evacuaciones debido al riesgo de inundaci\u00f3n en las ciudades de Ancenis, Rochefort-sur-Loire, varias localidades del departamento de Vend\u00e9e y localidades &#8230; <a title=\"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire\" class=\"read-more\" href=\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\" aria-label=\"Leer m\u00e1s sobre Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":1322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[],"class_list":["post-1317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire - AA-Floods<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire - AA-Floods\" \/>\n<meta property=\"og:description\" content=\"En la regi\u00f3n francesa de Pays de la Loire, donde se encuentra la Universit\u00e9 de Nantes, socia de AA-Floods, las fuertes lluvias ca\u00eddas desde principios hasta mediados de febrero del presente a\u00f1o provocaron inundaciones o evacuaciones debido al riesgo de inundaci\u00f3n en las ciudades de Ancenis, Rochefort-sur-Loire, varias localidades del departamento de Vend\u00e9e y localidades ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\" \/>\n<meta property=\"og:site_name\" content=\"AA-Floods\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-15T21:10:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-03T16:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\/\/aafloods.eu\/es\/#\/schema\/person\/0d2618ba76c2298bc6a16388f4a0a13b\"},\"headline\":\"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire\",\"datePublished\":\"2021-04-15T21:10:47+00:00\",\"dateModified\":\"2022-03-03T16:25:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\"},\"wordCount\":721,\"publisher\":{\"@id\":\"https:\/\/aafloods.eu\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg\",\"articleSection\":[\"Noticia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\",\"url\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\",\"name\":\"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire - AA-Floods\",\"isPartOf\":{\"@id\":\"https:\/\/aafloods.eu\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg\",\"datePublished\":\"2021-04-15T21:10:47+00:00\",\"dateModified\":\"2022-03-03T16:25:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage\",\"url\":\"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg\",\"contentUrl\":\"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg\",\"width\":900,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/aafloods.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aafloods.eu\/es\/#website\",\"url\":\"https:\/\/aafloods.eu\/es\/\",\"name\":\"AA-Floods\",\"description\":\"Prevention and action in case of flood\u200b\",\"publisher\":{\"@id\":\"https:\/\/aafloods.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aafloods.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aafloods.eu\/es\/#organization\",\"name\":\"AA-Floods\",\"url\":\"https:\/\/aafloods.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aafloods.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aafloods.eu\/wp-content\/uploads\/2019\/05\/cropped-favicon-aafloods2-2.png\",\"contentUrl\":\"https:\/\/aafloods.eu\/wp-content\/uploads\/2019\/05\/cropped-favicon-aafloods2-2.png\",\"width\":512,\"height\":228,\"caption\":\"AA-Floods\"},\"image\":{\"@id\":\"https:\/\/aafloods.eu\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/aafloods.eu\/es\/#\/schema\/person\/0d2618ba76c2298bc6a16388f4a0a13b\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/aafloods.eu\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b7beea78b23df5871686909a9acd0ab3d22dfa7814731cbafbbd9f8f0aa3bc83?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b7beea78b23df5871686909a9acd0ab3d22dfa7814731cbafbbd9f8f0aa3bc83?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\/\/aafloods.eu\/es\/author\/anabelen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire - AA-Floods","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/","og_locale":"es_ES","og_type":"article","og_title":"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire - AA-Floods","og_description":"En la regi\u00f3n francesa de Pays de la Loire, donde se encuentra la Universit\u00e9 de Nantes, socia de AA-Floods, las fuertes lluvias ca\u00eddas desde principios hasta mediados de febrero del presente a\u00f1o provocaron inundaciones o evacuaciones debido al riesgo de inundaci\u00f3n en las ciudades de Ancenis, Rochefort-sur-Loire, varias localidades del departamento de Vend\u00e9e y localidades ... Leer m\u00e1s","og_url":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/","og_site_name":"AA-Floods","article_published_time":"2021-04-15T21:10:47+00:00","article_modified_time":"2022-03-03T16:25:22+00:00","og_image":[{"width":900,"height":599,"url":"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#article","isPartOf":{"@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/aafloods.eu\/es\/#\/schema\/person\/0d2618ba76c2298bc6a16388f4a0a13b"},"headline":"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire","datePublished":"2021-04-15T21:10:47+00:00","dateModified":"2022-03-03T16:25:22+00:00","mainEntityOfPage":{"@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/"},"wordCount":721,"publisher":{"@id":"https:\/\/aafloods.eu\/es\/#organization"},"image":{"@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage"},"thumbnailUrl":"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg","articleSection":["Noticia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/","url":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/","name":"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire - AA-Floods","isPartOf":{"@id":"https:\/\/aafloods.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage"},"image":{"@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage"},"thumbnailUrl":"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg","datePublished":"2021-04-15T21:10:47+00:00","dateModified":"2022-03-03T16:25:22+00:00","breadcrumb":{"@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#primaryimage","url":"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg","contentUrl":"https:\/\/aafloods.eu\/wp-content\/uploads\/2021\/04\/foto-blog-abril-con-pie-esp-1.jpg","width":900,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/aafloods.eu\/es\/reflexionando-sobre-la-politica-de-inundaciones-francesa-en-la-region-de-pays-de-la-loire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aafloods.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Reflexionando sobre la pol\u00edtica de inundaciones francesa en la regi\u00f3n de Pays de la Loire"}]},{"@type":"WebSite","@id":"https:\/\/aafloods.eu\/es\/#website","url":"https:\/\/aafloods.eu\/es\/","name":"AA-Floods","description":"Prevention and action in case of flood\u200b","publisher":{"@id":"https:\/\/aafloods.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aafloods.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/aafloods.eu\/es\/#organization","name":"AA-Floods","url":"https:\/\/aafloods.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aafloods.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/aafloods.eu\/wp-content\/uploads\/2019\/05\/cropped-favicon-aafloods2-2.png","contentUrl":"https:\/\/aafloods.eu\/wp-content\/uploads\/2019\/05\/cropped-favicon-aafloods2-2.png","width":512,"height":228,"caption":"AA-Floods"},"image":{"@id":"https:\/\/aafloods.eu\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aafloods.eu\/es\/#\/schema\/person\/0d2618ba76c2298bc6a16388f4a0a13b","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aafloods.eu\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b7beea78b23df5871686909a9acd0ab3d22dfa7814731cbafbbd9f8f0aa3bc83?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b7beea78b23df5871686909a9acd0ab3d22dfa7814731cbafbbd9f8f0aa3bc83?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/aafloods.eu\/es\/author\/anabelen\/"}]}},"_links":{"self":[{"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/posts\/1317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/comments?post=1317"}],"version-history":[{"count":2,"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/posts\/1317\/revisions"}],"predecessor-version":[{"id":1327,"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/posts\/1317\/revisions\/1327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/media\/1322"}],"wp:attachment":[{"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/media?parent=1317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/categories?post=1317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aafloods.eu\/es\/wp-json\/wp\/v2\/tags?post=1317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}